{"id":60,"date":"2024-01-26T12:41:08","date_gmt":"2024-01-26T12:41:08","guid":{"rendered":"https:\/\/eurohinca.es\/?page_id=60"},"modified":"2026-05-13T10:18:53","modified_gmt":"2026-05-13T10:18:53","slug":"entreprise","status":"publish","type":"page","link":"https:\/\/eurohinca.com\/fr\/empresa\/","title":{"rendered":"Entreprise"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"60\" class=\"elementor elementor-60\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17129c1 e-flex e-con-boxed e-con e-parent\" data-id=\"17129c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b1429c elementor-widget elementor-widget-heading\" data-id=\"9b1429c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Entreprise<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcc94e3 e-flex e-con-boxed e-con e-parent\" data-id=\"bcc94e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8fcc37 elementor-widget elementor-widget-image\" data-id=\"c8fcc37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/LOGO-eurohinca-group.png\" class=\"attachment-full size-full wp-image-2053\" alt=\"ic\u00f4ne eurohinca\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6c7650 elementor-widget elementor-widget-heading\" data-id=\"b6c7650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Notre entreprise<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4208eab elementor-widget elementor-widget-heading\" data-id=\"4208eab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recherche + D\u00e9veloppement + Innovation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17c3207 e-flex e-con-boxed e-con e-child\" data-id=\"17c3207\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2265a9e elementor-widget elementor-widget-text-editor\" data-id=\"2265a9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eurohinca participe depuis plusieurs ann\u00e9es \u00e0 des programmes de RDI. Elle collabore avec des universit\u00e9s et des centres technologiques afin d'am\u00e9liorer la production et l'efficacit\u00e9 de toutes les activit\u00e9s de l'entreprise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ff4e28 e-grid e-con-boxed e-con e-child\" data-id=\"6ff4e28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a391345 elementor-widget elementor-widget-counter\" data-id=\"a391345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Ann\u00e9es d'exp\u00e9rience<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"28\" data-from-value=\"20\" data-delimiter=\",\">20<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce2f7e6 elementor-widget elementor-widget-counter\" data-id=\"ce2f7e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Travaux<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"250\" data-from-value=\"240\" data-delimiter=\",\">240<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cdef66 elementor-widget elementor-widget-counter\" data-id=\"6cdef66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Kilom\u00e8tres<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"120\" data-from-value=\"110\" data-delimiter=\",\">110<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b7e832f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7e832f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dec4144 elementor-invisible\" data-id=\"dec4144\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b75dfdb elementor-widget elementor-widget-image\" data-id=\"b75dfdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Tunel-de-dovelas-Playa-de-vias-Segmental-lining-shaft-1.jpg\" class=\"attachment-full size-full wp-image-1698\" alt=\"tunnels de voussoirs\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f3a6fb e-flex e-con-boxed e-con e-parent\" data-id=\"5f3a6fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c6c040 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"8c6c040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-078d21b\" data-id=\"078d21b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f9fa52 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1f9fa52\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>EUROHINCA couvre les besoins int\u00e9graux de tout projet de construction.<\/strong>&nbsp;En particulier, gr\u00e2ce \u00e0 l'application de techniques d'excavation souterraine sans tranch\u00e9e, EUROHINCA entreprend des projets, entre autres, des typologies suivantes :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f41b433 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"f41b433\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9missaires et immisaires sous-marins<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9missaires et immisaires sous-aquatiques<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ouvrages hydrauliques pour les collecteurs d'eau de rivi\u00e8re et d'eau de pluie, les syst\u00e8mes d'\u00e9gouts, etc.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e9seaux d'assainissement urbain<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Les passages sous les routes, les voies ferr\u00e9es ou toute superstructure existante<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-c3a525a e-flex e-con-boxed e-con e-parent\" data-id=\"c3a525a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-da3488b e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"da3488b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50e290e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"50e290e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il convient de souligner la capacit\u00e9 op\u00e9rationnelle d'EUROHINCA \u00e0 r\u00e9aliser un large \u00e9ventail de travaux, \u00e9tant donn\u00e9 qu'elle fait partie d'un puissant conglom\u00e9rat d'entreprises ayant diff\u00e9rentes sp\u00e9cialisations dans le secteur de la construction, par exemple :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a02c96c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"a02c96c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Travaux de terrassement et de g\u00e9nie civil (coul\u00e9es, puits, fondations, etc.)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Forage vertical (en aval)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Forage horizontal dirig\u00e9 ou HDD (Horizontal Directional Drilling)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Travaux maritimes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gestion des aquif\u00e8res (points de captage, drainage, etc.)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">B\u00e9tonnage complexe et de grand volume<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd83a60 e-con-full e-flex e-con e-child\" data-id=\"cd83a60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7e206bd e-grid e-con-boxed e-con e-child\" data-id=\"7e206bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a30fd0 e-flex e-con-boxed e-con e-child\" data-id=\"1a30fd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c52fe08 elementor-widget elementor-widget-image\" data-id=\"c52fe08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"599\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Obra-Civil-Trabajos-maritimos-de-rescate-de-Tuneladora-Civil-Works-Maritiem-works-for-TBM-rescue.jpg\" class=\"attachment-large size-large wp-image-1703\" alt=\"Travaux de sauvetage d&#039;un tunnelier en mer\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0beb799 e-flex e-con-boxed e-con e-child\" data-id=\"0beb799\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d42a8 elementor-widget elementor-widget-image\" data-id=\"e2d42a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Hinca-de-tuberia-Tunel-Pipe-jacking-tunnel.jpg\" class=\"attachment-large size-large wp-image-1705\" alt=\"Cuvette \u00e0 tuyau\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc085ec e-flex e-con-boxed e-con e-child\" data-id=\"fc085ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef35eab elementor-widget elementor-widget-image\" data-id=\"ef35eab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Hinca-de-tuberia-Estacion-intermedia-Pipe-Jacking-Intermediate-jacking-station-2.jpg\" class=\"attachment-large size-large wp-image-1706\" alt=\"Cuvette \u00e0 tuyau\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-803f473 e-flex e-con-boxed e-con e-child\" data-id=\"803f473\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a53f7dd elementor-widget elementor-widget-image\" data-id=\"a53f7dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"524\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Tuneladora-en-puerto-despues-de-emisarios-submarino-Tunnel-Boring-Machine-at-port-after-Seaoutfall.jpg\" class=\"attachment-large size-large wp-image-1704\" alt=\"Tunnelier au port apr\u00e8s le Seaoutfall - Tunnelier au port apr\u00e8s le Seaoutfall\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9b494a e-flex e-con-boxed e-con e-parent\" data-id=\"e9b494a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a788e6 elementor-widget elementor-widget-heading\" data-id=\"8a788e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ces derni\u00e8res ann\u00e9es, Eurohinca a pr\u00e9sent\u00e9 un certain nombre de projets de RDI, dont les suivants se distinguent :<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a492f68 e-flex e-con-boxed e-con e-parent\" data-id=\"a492f68\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2e38ee4 e-con-full e-flex e-con e-child\" data-id=\"2e38ee4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3370e97 e-grid e-con-boxed e-con e-child\" data-id=\"3370e97\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b0041c3 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b0041c3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a11be86 elementor-widget elementor-widget-image\" data-id=\"a11be86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"150\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Grupo-de-desplazamiento-2.jpg\" class=\"attachment-full size-full wp-image-484\" alt=\"groupe de d\u00e9placement\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e1a524 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3e1a524\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e2e7b0 elementor-widget elementor-widget-heading\" data-id=\"8e2e7b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.youtube.com\/watch?v=4_Mo3JOB4Nk&#038;t=2s\">Projet multidimensionnel de RDI dans les villes<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20307d2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"20307d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une initiative conjointe de l'industrie, des centres technologiques, des universit\u00e9s, des centres de recherche publics et priv\u00e9s et d'autres organisations, visant \u00e0 relever le d\u00e9fi auquel notre soci\u00e9t\u00e9 est confront\u00e9e : rendre les villes plus confortables, plus durables et plus modernes avec des espaces pour les personnes, en \u00e9liminant la plupart des nuisances dues au trafic et en promouvant les transports collectifs et sociaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-341bfe1 e-con-full e-flex e-con e-child\" data-id=\"341bfe1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-012c287 e-grid e-con-boxed e-con e-child\" data-id=\"012c287\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2e8f003 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"2e8f003\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef5ceb8 elementor-widget elementor-widget-image\" data-id=\"ef5ceb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"199\" height=\"150\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Grupo-de-desplazamiento-3.jpg\" class=\"attachment-full size-full wp-image-485\" alt=\"Groupe de d\u00e9placement\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-554cf71 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"554cf71\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c479234 elementor-widget elementor-widget-heading\" data-id=\"c479234\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.youtube.com\/watch?v=4_Mo3JOB4Nk&#038;t=2s\">Projet RDI sur les syst\u00e8mes de forage pour les tunneliers Hidroescudo.<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83fa122 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"83fa122\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Projet de d\u00e9veloppement d'un nouveau tunnelier bas\u00e9 sur le tunnelier traditionnel Hydroshield pour le fon\u00e7age de tubes, afin d'obtenir de meilleures performances de cet \u00e9quipement de forage co\u00fbteux dans les projets o\u00f9 l'on trouve des sols argileux et collants, o\u00f9 les tunneliers Hydroshield ont des difficult\u00e9s \u00e0 forer car ils ne peuvent pas pomper la boue argileuse vers l'ext\u00e9rieur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9838212 e-flex e-con-boxed e-con e-parent\" data-id=\"9838212\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57be733 elementor-widget elementor-widget-heading\" data-id=\"57be733\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eurohinca, sp\u00e9cialiste de la technologie sans tranch\u00e9e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b62b892 elementor-widget elementor-widget-text-editor\" data-id=\"b62b892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eurohinca r\u00e9alise des travaux de creusement de tunnels \u00e0 l'aide d'un tunnelier en utilisant le <strong>Technologie sans tranch\u00e9e.<\/strong>\u00a0Les Nations Unies ont reconnu ces technologies comme \u00e9tant respectueuses de l'environnement et durables sur le plan environnemental. Ces technologies nous permettent d'offrir des solutions techniques innovantes pour l'ex\u00e9cution de travaux de forage \u00e0 des fins diverses <strong>\u00a0sans perturber l'activit\u00e9 quotidienne des villes<\/strong>:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17da5a4 e-grid e-con-boxed e-con e-child\" data-id=\"17da5a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-86164e9 e-flex e-con-boxed e-con e-child\" data-id=\"86164e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afb8faa elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"afb8faa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Approvisionnement en eau et assainissement.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Gaz, \u00e9lectricit\u00e9, c\u00e2ble, fibre optique, r\u00e9seaux de t\u00e9l\u00e9communications, etc.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Syst\u00e8mes de drainage et d'\u00e9vacuation.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Les captages d'eau et les immisaires.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> \u00c9missaires sous-marins (assainissement, dessalement)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Passage souterrain vers les services publics existants, routes, chemins de fer, pistes d'a\u00e9roport, parcs, etc.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c48bf9 elementor-widget elementor-widget-text-editor\" data-id=\"0c48bf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Parmi les avantages des techniques de forage sans tranch\u00e9e (NO-DIG) par rapport aux technologies conventionnelles, les plus importants sont les suivants:\u00a0<b>augmentation de la production sur l'ensemble du site<\/b>\u00a0et la\u00a0<b>r\u00e9duction du temps d'ex\u00e9cution<\/b>\u00a0qui a un impact direct sur\u00a0<b>la r\u00e9duction des co\u00fbts \u00e9conomiques associ\u00e9s<\/b>\u00a0\u00e0\u00a0<b>la r\u00e9duction des \u00e9missions de CO<sub>2<\/sub><\/b>\u00a0ainsi que la r\u00e9duction du bruit et de la salet\u00e9 sur les chantiers de construction, ce qui aura pour effet de r\u00e9duire les \u00e9missions de gaz \u00e0 effet de serre\u00a0<b>et r\u00e9duit les nuisances caus\u00e9es \u00e0 la population<\/b>. Les autres avantages de la technologie sans tranch\u00e9e sont les suivants :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be03a00 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"be03a00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Moins de d\u00e9pendance \u00e0 l'\u00e9gard des facteurs environnementaux.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Co\u00fbt moins \u00e9lev\u00e9 en terrain rocheux.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Une plus grande flexibilit\u00e9 dans l'acheminement.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">S\u00e9curit\u00e9 accrue pour les travailleurs et les citoyens.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Am\u00e9lioration de la qualit\u00e9 de vie dans les villes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Moins de dommages aux services publics souterrains.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e9duction de l'impact sur l'environnement<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Il n'est pas n\u00e9cessaire d'abaisser le niveau de la nappe phr\u00e9atique.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e9duction du risque d'\u00e9tablissement.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Meilleure finition de la construction du tunnel.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5433d7b e-flex e-con-boxed e-con e-child\" data-id=\"5433d7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70442e1 e-flex e-con-boxed e-con e-child\" data-id=\"70442e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b38dc3 elementor-widget elementor-widget-image\" data-id=\"5b38dc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"509\" height=\"766\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/cruce-aeropuerto-eurohinca.jpg\" class=\"attachment-large size-large wp-image-486\" alt=\"travers\u00e9e de l&#039;a\u00e9roport\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcccfdf elementor-widget elementor-widget-text-editor\" data-id=\"fcccfdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eurohinca promeut \u00e9galement l'utilisation des technologies sans tranch\u00e9e en tant qu'outil cl\u00e9 pour le d\u00e9veloppement des <strong>smart cities<\/strong> -Villes intelligentes- bas\u00e9es sur le d\u00e9veloppement urbain durable, actuellement en plein essor en raison de ses multiples avantages environnementaux, \u00e9conomiques et sociaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddf44e4 elementor-widget elementor-widget-text-editor\" data-id=\"ddf44e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eurohinca est l'une des entreprises associ\u00e9es \u00e0 <strong>L'association ib\u00e9rique pour la technologie sans tranch\u00e9e.<\/strong> L'objectif de ce projet est de promouvoir la technologie sans tranch\u00e9e dans les travaux li\u00e9s \u00e0 la construction de canalisations pour tous les types de services.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-845fab9 e-flex e-con-boxed e-con e-parent\" data-id=\"845fab9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-734ca69 elementor-widget elementor-widget-heading\" data-id=\"734ca69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e9 et environnement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da8c664 elementor-widget elementor-widget-text-editor\" data-id=\"da8c664\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Depuis sa cr\u00e9ation, Europea de Hincas Teledirigidas, S.A.U., EUROHINCA, s'est toujours engag\u00e9e en faveur de <b>la qualit\u00e9 dans l'ex\u00e9cution des travaux et dans la gestion de l'entreprise<\/b> dans le but de se d\u00e9marquer des autres entreprises du secteur. De m\u00eame, l'engagement a \u00e9t\u00e9 pris d\u00e8s le d\u00e9part de d\u00e9velopper son activit\u00e9 dans <b>le respect de l'environnement<\/b>\u00a0afin de laisser le meilleur h\u00e9ritage possible aux g\u00e9n\u00e9rations futures. Compte tenu de ce qui pr\u00e9c\u00e8de, il a \u00e9t\u00e9 d\u00e9cid\u00e9 d'obtenir les certificats suivants\u00a0<b>ISO 9001:2015 et ISO 14001:2015<\/b>\u00a0avec\u00a0<b>AENOR.<\/b>&nbsp;l'un des certificateurs les plus importants et les plus rigoureux au monde. Les liens suivants permettent de t\u00e9l\u00e9charger les politiques de qualit\u00e9 et d'environnement d'Eurohinca ainsi que la certification d'AENOR :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3486d47 e-flex e-con-boxed e-con e-parent\" data-id=\"3486d47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a2f697 e-grid e-con-boxed e-con e-child\" data-id=\"6a2f697\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-855cb27 e-flex e-con-boxed e-con e-child\" data-id=\"855cb27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc08dc elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"5fc08dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/2_ISO9001.2015_EUROHINCA_IQNet_20260518_Quality.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf72a8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ebf72a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/2_ISO9001.2015_EUROHINCA_IQNet_20260518_Quality.pdf\" target=\"_blank\">Certificat de syst\u00e8me de gestion de la qualit\u00e9 (ISO 9001:2015)<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c4fb661 e-flex e-con-boxed e-con e-child\" data-id=\"c4fb661\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8b2516 elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"e8b2516\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/8_Integrated-Management-System-Policy_v.0.0.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8264295 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8264295\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/8_Integrated-Management-System-Policy_v.0.0.pdf\" target=\"_blank\">Politique de qualit\u00e9 et d'environnement<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c41694d e-flex e-con-boxed e-con e-child\" data-id=\"c41694d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-337fa4d elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"337fa4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/4_ISO14001.2015_EUROHINCA_IQNet_20260518_Environment.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f2de15 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5f2de15\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/4_ISO14001.2015_EUROHINCA_IQNet_20260518_Environment.pdf\" target=\"_blank\">Certificat de syst\u00e8me de gestion environnementale (ISO 14001:2015)<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-efa6a1e e-flex e-con-boxed e-con e-parent\" data-id=\"efa6a1e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fa758e elementor-widget elementor-widget-heading\" data-id=\"0fa758e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Indicateurs de performance environnementale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d9d78f elementor-widget elementor-widget-text-editor\" data-id=\"9d9d78f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eurohinca, par le biais de son manuel int\u00e9gr\u00e9 sur la qualit\u00e9 et l'environnement, d\u00e9finit la communication externe entre l'organisation et les parties int\u00e9ress\u00e9es qui sont li\u00e9es aux exigences l\u00e9gales en mati\u00e8re d'environnement et \u00e0 ses performances environnementales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e53dd7c e-flex e-con-boxed e-con e-parent\" data-id=\"e53dd7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-44d1879 e-grid e-con-boxed e-con e-child\" data-id=\"44d1879\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d7fcd2 e-flex e-con-boxed e-con e-child\" data-id=\"1d7fcd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3be54c0 e-flex e-con-boxed e-con e-child\" data-id=\"3be54c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb851f elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"2eb851f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2026\/04\/DESEMPENO-AMBIENTAL-Y-SST-EH.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-956c0b0 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"956c0b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2026\/04\/DESEMPENO-AMBIENTAL-Y-SST-EH.pdf\" target=\"_blank\">Rapport annuel int\u00e9gr\u00e9 2025<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fd5afe e-flex e-con-boxed e-con e-parent\" data-id=\"7fd5afe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fbcca4 elementor-widget elementor-widget-heading\" data-id=\"6fbcca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sant\u00e9 et s\u00e9curit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f1c113 elementor-widget elementor-widget-text-editor\" data-id=\"8f1c113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez EUROHINCA, rien n'est plus important que la\u00a0<b>s\u00e9curit\u00e9,&nbsp;<\/b>il est donc essentiel de s'engager en faveur d'une culture proactive. Un exemple de cette culture est le\u00a0<b>Syst\u00e8me de gestion de la sant\u00e9 et de la s\u00e9curit\u00e9\u00a0<\/b>que nous maintenons conform\u00e9ment \u00e0 la norme\u00a0<b>ISO 45001:2018&nbsp;<\/b>et certifi\u00e9e par\u00a0<b>AENOR.<\/b>&nbsp;Les liens suivants permettent de t\u00e9l\u00e9charger la politique de pr\u00e9vention des risques professionnels d'EUROHINCA et les certifications d'AENOR.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d93dcc e-flex e-con-boxed e-con e-parent\" data-id=\"2d93dcc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f8478e6 e-grid e-con-boxed e-con e-child\" data-id=\"f8478e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6eb7357 e-flex e-con-boxed e-con e-child\" data-id=\"6eb7357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30abb34 elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"30abb34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/8_Integrated-Management-System-Policy_v.0.0.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec081f6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ec081f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/8_Integrated-Management-System-Policy_v.0.0.pdf\" target=\"_blank\">Politique de pr\u00e9vention des risques professionnels<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3b2e45 e-flex e-con-boxed e-con e-child\" data-id=\"f3b2e45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64140ef elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"64140ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/6_ISO45001.2023_EUROHINCA_IQNetES-SST-0057-2017_2024-08-08_Safety.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b448644 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b448644\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2025\/03\/6_ISO45001.2023_EUROHINCA_IQNetES-SST-0057-2017_2024-08-08_Safety.pdf\" target=\"_blank\">Certificat de syst\u00e8me de gestion de la sant\u00e9 et de la s\u00e9curit\u00e9 au travail (ISO 45001:2018)<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-871d257 e-flex e-con-boxed e-con e-parent\" data-id=\"871d257\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76eb320 elementor-widget elementor-widget-heading\" data-id=\"76eb320\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Promouvoir un environnement de travail s\u00fbr<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d70a71 elementor-widget elementor-widget-text-editor\" data-id=\"0d70a71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La s\u00e9curit\u00e9 et le bien-\u00eatre des employ\u00e9s sont une priorit\u00e9 absolue pour l'entreprise, ce qui se refl\u00e8te dans l'\u00e9volution des principaux indicateurs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55e4051 e-flex e-con-boxed e-con e-parent\" data-id=\"55e4051\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0d863b7 e-grid e-con-boxed e-con e-child\" data-id=\"0d863b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9ead7b8 e-flex e-con-boxed e-con e-child\" data-id=\"9ead7b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95f4420 e-flex e-con-boxed e-con e-child\" data-id=\"95f4420\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cd7d4a elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"5cd7d4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2026\/04\/DESEMPENO-AMBIENTAL-Y-SST-EH.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efac624 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"efac624\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2026\/04\/DESEMPENO-AMBIENTAL-Y-SST-EH.pdf\" target=\"_blank\">Rapport annuel int\u00e9gr\u00e9 2025<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14463af e-flex e-con-boxed e-con e-parent\" data-id=\"14463af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cdf838d elementor-widget elementor-widget-heading\" data-id=\"cdf838d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mission, vision et valeurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbf213a elementor-widget elementor-widget-text-editor\" data-id=\"cbf213a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>EUROHINCA a pour mission d'\u00e9tudier, d'appliquer et de d\u00e9velopper des solutions techniques pour la construction de tunnels, au niveau international, avec des professionnels hautement qualifi\u00e9s en raison de leur sp\u00e9cialisation et de leur exp\u00e9rience.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b2d92f e-grid e-con-boxed e-con e-child\" data-id=\"9b2d92f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-17363bb e-flex e-con-boxed e-con e-child\" data-id=\"17363bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1e2ef2a e-flex e-con-boxed e-con e-child\" data-id=\"1e2ef2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-033094c elementor-widget elementor-widget-heading\" data-id=\"033094c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Notre vision<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8aab697 elementor-widget elementor-widget-text-editor\" data-id=\"8aab697\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez EUROHINCA, nous voulons \u00eatre en mesure de fournir la meilleure solution technique, qualitative et \u00e9conomique \u00e0 nos clients dans le monde entier, en les fid\u00e9lisant et en promouvant une culture d'am\u00e9lioration continue en mati\u00e8re d'innovation, de ressources humaines, de s\u00e9curit\u00e9 et d'environnement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfbf716 e-con-full e-flex e-con e-child\" data-id=\"bfbf716\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f14fa2 elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"5f14fa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/mision-vision-valores.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f13a302 e-con-full e-flex e-con e-child\" data-id=\"f13a302\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ba4e26 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9ba4e26\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/mision-vision-valores.pdf\" target=\"_blank\">D\u00e9claration de mission, de vision et de valeurs<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87df38c e-flex e-con-boxed e-con e-child\" data-id=\"87df38c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fdf83f0 e-flex e-con-boxed e-con e-child\" data-id=\"fdf83f0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73503a7 elementor-widget elementor-widget-heading\" data-id=\"73503a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos valeurs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75023f1 elementor-widget elementor-widget-text-editor\" data-id=\"75023f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Rien n'est plus important que la s\u00e9curit\u00e9.<\/li><li>Nos professionnels disposent des qualifications et de l'exp\u00e9rience n\u00e9cessaires pour r\u00e9aliser d'excellentes performances.<\/li><li>Gestion des connaissances.<\/li><li>Nous connaissons et analysons les besoins de nos clients.<\/li><li>Code de conduite.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c795aad e-con-full e-flex e-con e-child\" data-id=\"c795aad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8eb9600 elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"8eb9600\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-float\" href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/valores-transcanada.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2ce1bd e-con-full e-flex e-con e-child\" data-id=\"a2ce1bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-558b40f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"558b40f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/valores-transcanada.pdf\" target=\"_blank\">D\u00e9claration de valeurs de TransCanada<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a30d8ff e-flex e-con-boxed e-con e-parent\" data-id=\"a30d8ff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69985ed elementor-widget elementor-widget-heading\" data-id=\"69985ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">N'h\u00e9sitez pas \u00e0 nous contacter, nous collaborerons et concevrons les meilleurs projets.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-129ea47 e-flex e-con-boxed e-con e-parent\" data-id=\"129ea47\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f3bd50f e-con-full e-flex e-con e-child\" data-id=\"f3bd50f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffff00b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ffff00b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" height=\"81.809\" viewbox=\"0 0 85.708 81.809\" width=\"85.708\"><clippath id=\"a\"><path d=\"m0 0h85.708v81.809h-85.708z\"><\/path><\/clippath><g clip-path=\"url(#a)\"><path d=\"m85.708 70.466a8.934 8.934 0 0 0 -.25-2.23 8.155 8.155 0 0 0 -8.458-6.225c-.9.021-1.009-.243-1-1.033.031-6.426.018-12.853.017-19.279 0-3.06-1.56-4.631-4.6-4.632h-8.382v-15.239l.006-4.6a5.438 5.438 0 0 0 -1.745-4.089q-5.684-5.476-11.346-10.966a1.664 1.664 0 0 0 -1.886-.417c-4.564 1.544-9.148 3.057-13.722 4.582-2.337.779-4.672 1.565-7.11 2.383 0-1.618.015-3.142 0-4.665a3.933 3.933 0 0 0 -3.967-4.056 3.84 3.84 0 0 0 -4.01 4.055c-.01 2.2-.028 4.4.014 6.593a.877.877 0 0 1 -.762 1.025c-1.381.411-2.733.916-4.1 1.371-3.07 1.024-4.295 2.707-4.295 5.929q0 21.074.014 42.148c0 .645-.1.871-.825.927a10.247 10.247 0 0 0 -9.061 8.471 52.192 52.192 0 0 0 -.13 8.5 2.814 2.814 0 0 0 2.046 2.592 5.055 5.055 0 0 0 1.812.2h64.932c4.451 0 8.9.009 13.353 0a3.161 3.161 0 0 0 3.447-3.499c0-2.615 0-5.23 0-7.846m-75.581 8.319c.005.4-.12.528-.521.525-2.053-.017-4.107-.012-6.16-.007-.634 0-.887-.3-.876-.928.022-1.276.029-2.553 0-3.829-.012-.465.161-.545.573-.535 1.081.025 2.164.008 3.247.008 1.054 0 2.109.015 3.163-.007.4-.008.595.05.584.528-.033 1.414-.023 2.83 0 4.245m0-7.865c.006.465-.117.623-.6.607-1.053-.036-2.108-.011-3.162-.011s-2.109-.022-3.162.01c-.481.015-.586-.094-.509-.595a7.915 7.915 0 0 1 6.754-6.41c.464-.044.689 0 .677.575-.04 1.941-.029 3.883-.005 5.824m11.648-67.12a1.237 1.237 0 0 1 1.185-1.274 1.428 1.428 0 0 1 1.657.931 2.693 2.693 0 0 1 .112.817c.01 1.555-.015 3.11.018 4.664.01.463-.114.7-.569.828-.79.224-1.565.5-2.411.78 0-2.31-.017-4.528.009-6.746m4.238 75.511c-1.221-.036-2.444-.034-3.665 0-.488.013-.6-.158-.6-.617q.028-4.249 0-8.5a.788.788 0 0 1 .635-.911c1.257-.336 2.508-.7 3.756-1.062.428-.125.52.033.516.436-.017 1.694-.007 3.388-.007 5.082 0 1.638-.02 3.277.011 4.915.01.514-.138.671-.654.655m7.4 0c-1.193-.035-2.389-.027-3.582 0-.466.009-.693-.064-.689-.624.026-3.583.019-7.166 0-10.748a.59.59 0 0 1 .511-.692c1.259-.329 2.514-.675 3.759-1.052.6-.183.7.048.691.591-.026 2-.01 4-.01 6 0 1.944-.022 3.889.014 5.832.011.56-.159.713-.7.7m-13.89-47.79a1.287 1.287 0 0 0 1.581.383c1.842-.611 3.679-1.239 5.519-1.857q7.884-2.648 15.769-5.29c1.55-.518 3.116-.986 4.658-1.525.493-.172.558-.04.554.408-.017 1.753-.031 3.506.007 5.258.012.541-.3.616-.678.744q-9.468 3.149-18.93 6.314-3.787 1.264-7.574 2.531c-.583.194-1.075.475-1.148 1.164-.106 1 .778 1.6 1.878 1.237 2.817-.933 5.627-1.885 8.439-2.83q6.346-2.133 12.693-4.264c1.577-.526 3.171-1 4.743-1.542.448-.154.578-.113.572.384-.022 1.753-.033 3.506.006 5.258.012.535-.275.629-.667.757-3.028.991-6.1 1.88-9.067 3.022-5.758 2.213-11.668 3.973-17.485 6-.909.318-1.307.954-1.062 1.684s.942 1 1.864.689c6.94-2.318 13.868-4.681 20.823-6.951 1.7-.553 3.325-1.279 5.019-1.833.47-.154.569-.083.564.393-.019 1.808-.031 3.617.007 5.425.011.539-.289.623-.675.751q-8.007 2.658-16.015 5.331c-.184.061-.374.111-.552.187a1.219 1.219 0 0 0 -.781 1.54 1.187 1.187 0 0 0 1.579.806c2.136-.69 4.26-1.422 6.391-2.127 3.13-1.036 6.268-2.052 9.392-3.106.513-.172.658-.14.657.449q-.024 13.856 0 27.711c0 .57-.185.69-.717.686q-4.8-.035-9.6 0c-.561 0-.689-.166-.686-.7.022-3.95-.052-7.9.037-11.851a2.9 2.9 0 0 0 -3.92-2.977c-3.57 1.121-7.2 2.041-10.81 3.051a3.145 3.145 0 0 0 -2.637 3.505c0 2.726-.02 5.453.014 8.179.007.606-.117.816-.766.8-1.7-.049-3.4-.052-5.091 0-.691.022-.808-.221-.807-.848q.026-17.278.013-34.556 0-12.52 0-25.04c0-1.987.591-2.8 2.48-3.434q13.559-4.556 27.118-9.11c1.752-.587 3.52-1.125 5.363-1.712v6.471c0 .5-.42.443-.7.539q-8.2 2.743-16.407 5.474-4.971 1.66-9.936 3.338a1.721 1.721 0 0 0 -1.1.688 1.186 1.186 0 0 0 .085 1.4 1.3 1.3 0 0 0 1.588.359q2.723-.9 5.441-1.826 7.8-2.629 15.607-5.259c1.576-.528 3.17-1 4.741-1.545.534-.184.714-.155.7.478q-.061 2.5 0 5.007c.014.559-.209.741-.7.9q-6.991 2.295-13.966 4.637-6.193 2.07-12.379 4.16a1.838 1.838 0 0 0 -1.062.607 1.185 1.185 0 0 0 .015 1.474m48.369 47.789c-2.864-.019-5.728-.009-8.592-.009-2.836 0-5.673-.014-8.509.012-.549.005-.718-.146-.7-.7.039-1.334.033-2.669 0-4-.011-.474.128-.6.6-.6q8.634.023 17.268 0c.455 0 .622.1.61.588-.033 1.361-.039 2.725 0 4.086.016.552-.2.63-.679.627m.685-8.715c.011.771-.206.942-.953.937q-8.382-.049-16.765 0c-.639 0-.775-.171-.772-.785.026-5.088.015-10.176.015-15.264 0-5.032.012-10.065-.015-15.1 0-.645.149-.833.815-.831 6.867.026 13.735.015 20.6.017 1.544 0 2.02.491 2.02 2.064 0 6.756-.007 13.512.015 20.268a1.05 1.05 0 0 1 -.638 1.077 8.056 8.056 0 0 0 -4.32 7.617m14.648 7.827c.008.6-.255.878-.842.878q-5.42 0-10.84.006c-.348 0-.493-.106-.489-.477.016-1.445.028-2.891 0-4.335-.012-.546.31-.475.642-.475q2.751 0 5.5 0c1.779 0 3.558.018 5.336-.011.512-.008.727.081.7.663-.05 1.249-.027 2.5-.01 3.751m0-7.25c-.037.475-.351.337-.593.338-1.835.009-3.669 0-5.5 0-1.807 0-3.613-.007-5.42.005-.4 0-.637 0-.666-.549-.257-4.811 3.993-7.637 8.45-6.11 2.446.838 3.977 3.17 3.733 6.311\" fill=\"#00214e\"><\/path><path d=\"m36.594 35.326q6.19-2.078 12.379-4.16 6.978-2.334 13.967-4.637c.488-.16.711-.343.7-.9q-.063-2.5 0-5.007c.015-.634-.165-.663-.7-.478-1.571.542-3.165 1.017-4.74 1.546q-7.807 2.619-15.607 5.259-2.72.917-5.441 1.826a1.3 1.3 0 0 1 -1.587-.359 1.184 1.184 0 0 1 -.085-1.4 1.72 1.72 0 0 1 1.1-.689q4.969-1.666 9.935-3.338 8.2-2.74 16.407-5.473c.285-.1.706-.039.7-.539 0-2.133 0-4.267 0-6.471-1.843.587-3.611 1.125-5.363 1.712q-13.563 4.544-27.119 9.11c-1.888.635-2.479 1.447-2.479 3.435q0 12.52 0 25.04 0 17.278-.013 34.555c0 .627.117.87.808.848 1.7-.054 3.395-.051 5.09 0 .65.019.774-.191.766-.8-.033-2.726-.017-5.453-.014-8.18a3.146 3.146 0 0 1 2.637-3.505c3.606-1.009 7.239-1.93 10.81-3.051a2.9 2.9 0 0 1 3.925 2.974c-.089 3.949-.015 7.9-.037 11.852 0 .538.125.709.686.7q4.8-.04 9.6 0c.532 0 .718-.117.718-.686q-.026-13.855 0-27.711c0-.589-.144-.622-.657-.449-3.125 1.054-6.262 2.07-9.392 3.106-2.132.705-4.255 1.437-6.391 2.126a1.187 1.187 0 0 1 -1.579-.806 1.219 1.219 0 0 1 .781-1.54c.178-.076.367-.125.551-.187q8.007-2.668 16.015-5.329c.387-.128.686-.212.675-.751-.038-1.807-.026-3.617-.007-5.425 0-.476-.094-.547-.564-.393-1.694.554-3.321 1.28-5.019 1.833-6.959 2.268-13.887 4.631-20.828 6.954-.922.308-1.62.037-1.863-.689s.152-1.366 1.062-1.684c5.818-2.032 11.727-3.791 17.485-6 2.971-1.142 6.039-2.031 9.067-3.022.392-.128.679-.222.667-.757-.039-1.752-.028-3.506-.006-5.258.006-.5-.123-.537-.571-.384-1.572.539-3.166 1.015-4.743 1.542q-6.355 2.114-12.698 4.258c-2.812.945-5.623 1.9-8.439 2.83-1.1.364-1.983-.232-1.877-1.237.073-.69.564-.97 1.147-1.165q3.788-1.262 7.574-2.531 9.464-3.16 18.93-6.314c.383-.127.69-.2.679-.744-.038-1.752-.024-3.505-.007-5.258 0-.448-.062-.58-.554-.408-1.542.539-3.108 1.007-4.658 1.525q-7.887 2.637-15.769 5.29c-1.84.618-3.676 1.246-5.519 1.857a1.287 1.287 0 0 1 -1.58-.383 1.186 1.186 0 0 1 -.016-1.474 1.839 1.839 0 0 1 1.062-.607m-.312 27.305c1.491-.519 2.985-1.028 4.491-1.5a1.249 1.249 0 0 1 1.669 1.2 1.292 1.292 0 0 1 -.912 1.178c-1.492.515-2.986 1.028-4.49 1.506a1.256 1.256 0 1 1 -.757-2.383\" fill=\"#00a3dd\" transform=\"translate(-16.042 -5.88)\"><\/path><path d=\"m137.251 112.254c-.021-6.756-.013-13.512-.014-20.268 0-1.573-.476-2.064-2.02-2.064-6.867 0-13.735.009-20.6-.017-.667 0-.819.187-.815.831.027 5.032.015 10.065.015 15.1 0 5.088.011 10.176-.015 15.264 0 .614.133.788.772.785q8.383-.042 16.765 0c.747 0 .963-.166.953-.937a8.056 8.056 0 0 1 4.323-7.614 1.049 1.049 0 0 0 .638-1.077m-20.053-16.986a2.034 2.034 0 0 1 2.045-2.091q6.175-.043 12.351 0a2.019 2.019 0 0 1 2.064 1.991 25.539 25.539 0 0 1 .007 3.168 2.032 2.032 0 0 1 -2.178 2.047c-2 .032-4.005.009-6.008.009-1.947 0-3.895.009-5.841 0a2.141 2.141 0 0 1 -2.446-2.453c-.005-.89-.019-1.781.007-2.67m8.227 22.275a2.029 2.029 0 0 1 -2.055 1.988c-.694.026-1.391 0-2.086 0-.668 0-1.336.019-2 0a2.053 2.053 0 0 1 -2.079-2.057q-.048-1.542 0-3.087a2.012 2.012 0 0 1 2.065-2.055q2.043-.051 4.089 0a2 2 0 0 1 2.076 2.042c.04 1.055.042 2.115-.007 3.17m8.24-9.687a2.031 2.031 0 0 1 -2.178 2.045c-2.03.026-4.061.007-6.092.008-1.92 0-3.839.009-5.758 0a2.135 2.135 0 0 1 -2.445-2.45c-.005-.89-.019-1.781.007-2.67a2.028 2.028 0 0 1 2.045-2.09q6.175-.044 12.35 0a2.026 2.026 0 0 1 2.065 1.994 25.542 25.542 0 0 1 .007 3.168\" fill=\"#00a3dd\" transform=\"translate(-63.732 -50.349)\"><\/path><g fill=\"#f6f6f6\"><path d=\"m132.283 168.8c.012-.488-.154-.589-.61-.588q-8.634.022-17.267 0c-.472 0-.612.127-.6.6.031 1.334.037 2.67 0 4-.016.554.153.705.7.7 2.836-.026 5.673-.012 8.509-.012 2.864 0 5.728-.01 8.592.01.478 0 .7-.074.679-.627-.04-1.361-.035-2.725 0-4.087\" transform=\"translate(-63.733 -94.206)\"><\/path><path d=\"m169.868 146.9c-4.457-1.527-8.707 1.3-8.45 6.11.029.544.265.551.666.549 1.807-.012 3.613 0 5.42 0h5.5c.242 0 .556.137.593-.338.245-3.141-1.287-5.473-3.733-6.311\" transform=\"translate(-90.393 -82.034)\"><\/path><path d=\"m172.927 168.212c-1.778.029-3.558.011-5.336.011q-2.751 0-5.5 0c-.333 0-.654-.072-.642.475.033 1.445.021 2.891 0 4.335 0 .371.141.478.489.477q5.42-.011 10.84-.006c.587 0 .85-.282.842-.878-.017-1.25-.04-2.5.011-3.751.023-.582-.192-.671-.7-.663\" transform=\"translate(-90.414 -94.204)\"><\/path><path d=\"m71.19 156.963c0-2-.015-4 .01-6 .007-.543-.088-.774-.691-.592-1.245.377-2.5.723-3.759 1.052a.591.591 0 0 0 -.511.692c.015 3.583.022 7.165 0 10.748 0 .561.222.634.689.624 1.194-.023 2.389-.032 3.582 0 .539.016.709-.137.7-.7-.036-1.943-.014-3.888-.014-5.832\" transform=\"translate(-37.094 -84.179)\"><\/path><path d=\"m54.333 160.533c0-1.694-.01-3.388.007-5.082 0-.4-.088-.561-.516-.436-1.249.367-2.5.726-3.757 1.062a.788.788 0 0 0 -.635.911q.022 4.249 0 8.5c0 .459.107.63.6.617 1.221-.033 2.444-.035 3.665 0 .516.015.664-.141.654-.655-.032-1.638-.012-3.277-.012-4.915\" transform=\"translate(-27.682 -86.789)\"><\/path><path d=\"m12.8 168.219c-1.054.022-2.109.008-3.163.008-1.082 0-2.165.017-3.246-.008-.412-.01-.585.07-.573.535.033 1.275.027 2.553 0 3.829-.011.628.241.93.876.928 2.053-.005 4.107-.01 6.16.007.4 0 .526-.128.521-.525-.019-1.415-.028-2.831 0-4.245.011-.478-.184-.536-.583-.528\" transform=\"translate(-3.255 -94.207)\"><\/path><path d=\"m12.849 146.635a7.914 7.914 0 0 0 -6.758 6.409c-.077.5.028.609.509.595 1.053-.032 2.108-.01 3.162-.01s2.109-.025 3.162.011c.481.016.6-.142.6-.606-.024-1.941-.035-3.884.005-5.824.012-.577-.213-.618-.677-.574\" transform=\"translate(-3.398 -82.113)\"><\/path><\/g><path d=\"m51.865 12.961c.456-.129.579-.365.569-.828-.033-1.554-.007-3.109-.018-4.663a2.692 2.692 0 0 0 -.112-.817 1.428 1.428 0 0 0 -1.657-.931 1.237 1.237 0 0 0 -1.185 1.274c-.026 2.218-.009 4.436-.009 6.746.846-.277 1.621-.557 2.411-.78\" fill=\"#f5f5f5\" transform=\"translate(-27.693 -3.192)\"><\/path><path d=\"m45.487 129.377c1.5-.478 3-.991 4.49-1.506a1.291 1.291 0 0 0 .912-1.178 1.249 1.249 0 0 0 -1.669-1.2c-1.505.474-3 .983-4.491 1.5a1.256 1.256 0 1 0 .757 2.383\" fill=\"#00214e\" transform=\"translate(-24.491 -70.242)\"><\/path><path d=\"m135.905 118.959q-6.175-.037-12.35 0a2.028 2.028 0 0 0 -2.045 2.09c-.026.889-.012 1.78-.007 2.67a2.136 2.136 0 0 0 2.445 2.45c1.92.01 3.839 0 5.758 0 2.03 0 4.061.018 6.092-.008a2.031 2.031 0 0 0 2.178-2.045 25.542 25.542 0 0 0 -.007-3.168 2.026 2.026 0 0 0 -2.065-1.994m-1.868 4.712h-4.416c-1.639 0-3.278-.017-4.917.01-.505.009-.723-.072-.715-.66.023-1.57-.01-1.57 1.541-1.57 3.083 0 6.167.016 9.25-.015.59-.006.743.16.732.739-.027 1.5 0 1.5-1.475 1.5\" fill=\"#00214e\" transform=\"translate(-68.041 -66.61)\"><\/path><path d=\"m123.948 104.539c1.947.012 3.895 0 5.841 0 2 0 4.006.024 6.009-.008a2.032 2.032 0 0 0 2.177-2.047 25.459 25.459 0 0 0 -.007-3.168 2.019 2.019 0 0 0 -2.064-1.991q-6.175-.039-12.351 0a2.034 2.034 0 0 0 -2.044 2.091c-.026.889-.013 1.78-.007 2.67a2.141 2.141 0 0 0 2.446 2.453m1.506-4.727h4.253c1.7 0 3.391.017 5.086-.01.506-.008.729.072.72.664-.022 1.572.011 1.572-1.57 1.572-3.058 0-6.116-.018-9.173.015-.61.007-.8-.124-.783-.765.046-1.474.008-1.476 1.466-1.476\" fill=\"#00214e\" transform=\"translate(-68.04 -54.493)\"><\/path><path d=\"m127.66 140.854q-2.043-.05-4.089 0a2.011 2.011 0 0 0 -2.065 2.055q-.045 1.542 0 3.087a2.054 2.054 0 0 0 2.079 2.057c.667.023 1.335 0 2 0 .7 0 1.392.021 2.086 0a2.029 2.029 0 0 0 2.055-1.988c.049-1.055.047-2.115.007-3.17a2 2 0 0 0 -2.077-2.042m-.4 4.36c-.044.315-.176.346-.424.344-.8-.007-1.606-.013-2.408 0-.308.006-.478-.074-.431-.412a.4.4 0 0 0 0-.083c-.1-1.722-.1-1.722 1.7-1.722 1.68 0 1.8.159 1.566 1.87\" fill=\"#00214e\" transform=\"translate(-68.035 -78.869)\"><\/path><path d=\"m137.955 124.613c-3.083.03-6.167.014-9.25.014-1.55 0-1.518 0-1.541 1.57-.009.589.209.669.714.661 1.639-.028 3.278-.011 4.917-.01h4.417c1.477 0 1.448 0 1.475-1.5.011-.579-.142-.744-.732-.739\" fill=\"#f6f6f6\" transform=\"translate(-71.216 -69.787)\"><\/path><path d=\"m127.942 105.233c3.057-.033 6.115-.015 9.173-.015 1.581 0 1.548 0 1.57-1.572.008-.593-.214-.672-.72-.664-1.7.026-3.391.01-5.086.01h-4.253c-1.458 0-1.42 0-1.466 1.475-.02.642.173.772.783.766\" fill=\"#f6f6f6\" transform=\"translate(-71.212 -57.673)\"><\/path><path d=\"m128.857 146.546c-1.792 0-1.792 0-1.7 1.722a.4.4 0 0 1 0 .083c-.048.338.122.418.431.412.8-.016 1.606-.009 2.409 0 .247 0 .379-.028.423-.344.235-1.711.115-1.87-1.565-1.87\" fill=\"#f6f6f6\" transform=\"translate(-71.196 -82.07)\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAdministrations\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8a7bf elementor-widget elementor-widget-text-editor\" data-id=\"cc8a7bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eurohinca collabore \u00e0 la diffusion des technologies par sa pr\u00e9sence dans des congr\u00e8s, des masters, des associations et des articles dans des revues sp\u00e9cialis\u00e9es.<\/p><p>Nous sommes heureux de r\u00e9pondre aux questions des diff\u00e9rentes administrations sur la faisabilit\u00e9 et les meilleures solutions pour des projets sp\u00e9cifiques.<\/p><p>En outre, Eurohinca a \u00e9t\u00e9 class\u00e9e comme entrepreneur g\u00e9n\u00e9ral de l'\u00c9tat pour l'adjudication directe de travaux de creusement de tunnels.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03429dc e-con-full e-flex e-con e-child\" data-id=\"03429dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a33274 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9a33274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" height=\"89.966\" viewbox=\"0 0 89.929 89.966\" width=\"89.929\"><clippath id=\"a\"><path d=\"m0 0h89.929v89.966h-89.929z\"><\/path><\/clippath><g clip-path=\"url(#a)\"><path d=\"m34.028 35.836c-3.454-3.449-4.381-7.636-4.138-12.216a6.521 6.521 0 0 1 .009-.778c.145-.821-.256-.968-.973-.928-.971.054-1.948.031-2.921 0a1.977 1.977 0 1 1 .018-3.95c1.071-.025 2.144-.03 3.213 0 .493.015.651-.125.692-.64a13.815 13.815 0 0 1 8.438-12.198.731.731 0 0 0 .51-.8c-.035-.745-.036-1.494 0-2.239a1.97 1.97 0 0 1 2.1-2.064q3.992-.041 7.985 0c1.279.014 2.222.817 2.053 2.067-.286 2.112.633 3.07 2.4 4.113a13.141 13.141 0 0 1 6.555 10.87c.063.825.353.94 1.042.9.906-.049 1.817-.022 2.726-.009 1.391.019 2.259.8 2.246 2s-.878 1.943-2.288 1.96c-.974.011-1.95.042-2.921-.011-.616-.034-.757.176-.754.764a25.5 25.5 0 0 1 -.451 6.776 14.4 14.4 0 0 1 -3.7 6.435 22.549 22.549 0 0 1 8.273 1.568 20.94 20.94 0 0 1 10.05 8.134 21.735 21.735 0 0 1 3.58 9.752c.053.548.234.7.769.7a19.886 19.886 0 0 1 3.4.1 5.963 5.963 0 0 1 4.993 5.748c.02 1.136.027 2.273 0 3.408-.014.512.079.73.672.746 1.707.046 2.315.7 2.319 2.407q.014 4.577 0 9.155c-.007 1.633-.663 2.319-2.28 2.343-.535.008-.735.127-.713.695.043 1.1.021 2.207.01 3.311a5.945 5.945 0 0 1 -5.722 5.965c-.292.015-.584.019-.876.019q-35.4 0-70.8.028c-3.7.008-6.125-2.361-6.49-5.176a22.658 22.658 0 0 1 -.054-3.696c.028-.791-.049-1.224-1.046-1.165a1.777 1.777 0 0 1 -1.926-1.873q-.056-5.063 0-10.128c.014-1.2.809-1.888 2.135-1.881.7 0 .874-.221.838-.882-.055-1-.019-2.012-.012-3.018a5.991 5.991 0 0 1 5.9-6.109c.81-.034 1.625-.039 2.434 0 .561.028.76-.133.839-.731a21.8 21.8 0 0 1 16.138-18.665 24.175 24.175 0 0 1 2.762-.534c.925-.131 1.862-.176 2.966-.274\" fill=\"#00214e\"><\/path><path d=\"m52.638 126.342h35.343c2.032 0 2.649.627 2.653 2.688 0 .844-.035 1.69.013 2.531.033.589-.173.759-.752.822a6.949 6.949 0 0 0 .126 13.835c.542.056.631.259.62.719-.023.973 0 1.947-.01 2.921-.025 1.676-.77 2.407-2.466 2.407q-21.08 0-42.159 0h-28.721c-1.955 0-2.644-.681-2.653-2.612 0-.909.018-1.818-.009-2.726-.013-.471.1-.655.63-.709a6.949 6.949 0 0 0 .107-13.836c-.594-.065-.769-.259-.74-.833.044-.874.009-1.752.012-2.628.009-1.92.661-2.579 2.565-2.579q17.721 0 35.441 0\" fill=\"#00a3dd\" transform=\"translate(-7.67 -66.294)\"><\/path><path d=\"m45.723 86.075v6.743c0 1.59.725 2.379 2.28 2.381q14.746.02 29.492 0a2.052 2.052 0 0 0 2.314-2.35c.008-2.23 0-4.461 0-6.835a17.272 17.272 0 0 1 7.7 5.48 19.734 19.734 0 0 1 3.484 6.447c.242.837.369 1.707.592 2.55.133.5.048.745-.519.673a3.95 3.95 0 0 0 -.486 0q-27.837 0-55.675.016c-.817 0-1.108-.069-.917-1.029a20.141 20.141 0 0 1 2.87-7.054 17.234 17.234 0 0 1 8.4-6.888c.114-.045.237-.069.466-.134\" fill=\"#f6f6f6\" transform=\"translate(-17.804 -45.134)\"><\/path><path d=\"m82.38 46.114c3.374 0 6.75.028 10.124-.02.793-.011.986.234.943.977a34.5 34.5 0 0 1 -.219 5.046 9.951 9.951 0 0 1 -9.14 7.942 13.869 13.869 0 0 1 -6.419-.682 9.721 9.721 0 0 1 -6.31-8.894c-.072-1.2.021-2.4-.043-3.6-.037-.693.253-.783.843-.779 3.407.023 6.814.011 10.221.011\" fill=\"#f6f6f6\" transform=\"translate(-37.419 -24.186)\"><\/path><path d=\"m76.206 13.7c.186.185.079.425.113.637a2.03 2.03 0 0 0 2.1 1.873 2.006 2.006 0 0 0 1.9-2.079c.038-1.654.052-3.311-.007-4.964-.027-.759.178-1.029.95-.945 1.052.115 2.474-.445 3.069.218.521.581.14 1.974.15 3.009.007.779 0 1.557 0 2.336.011 1.473.752 2.391 1.951 2.426 1.18.035 1.929-.765 2.071-2.21.009-.095.033-.188.068-.384a8.437 8.437 0 0 1 2.772 2.4 9.98 9.98 0 0 1 2.1 5.449c.048.6-.118.77-.731.769q-10.318-.033-20.636-.009c-.428 0-.711.008-.718-.591a9.825 9.825 0 0 1 4.848-7.935\" fill=\"#00a3dd\" transform=\"translate(-37.441 -4.255)\"><\/path><path d=\"m80.1 89.892c-4.055 0-8.11-.015-12.165.015-.662 0-.9-.143-.873-.846.056-1.425.059-2.856 0-4.281-.029-.678.251-.847.828-.84.356 0 .713-.035 1.069-.035q11.192 0 22.385 0c1.878 0 1.877.018 1.877 1.848 0 1.1-.045 2.209.016 3.308.039.707-.215.849-.874.844-4.087-.029-8.175-.015-12.263-.015\" fill=\"#00a3dd\" transform=\"translate(-35.188 -44.026)\"><\/path><g fill=\"#f6f6f6\"><path d=\"m8.219 150.405c0-.944.035-1.724-.012-2.5-.032-.534.166-.66.66-.636.776.038 1.555 0 2.332.013a2.985 2.985 0 0 1 3.018 2.817 3.062 3.062 0 0 1 -2.6 3.138 1.616 1.616 0 0 1 -.289.036c-1-.018-2.3.334-2.908-.164-.643-.528-.1-1.884-.2-2.706\" transform=\"translate(-4.248 -77.275)\"><\/path><path d=\"m174.229 150.157c0 .778-.023 1.556.009 2.332.019.481-.092.709-.634.678-.775-.044-1.555.013-2.331-.019a3.063 3.063 0 0 1 -3.044-3.027 2.969 2.969 0 0 1 3.164-2.957c.926.006 2.161-.415 2.69.177.456.51.128 1.721.146 2.622z\" transform=\"translate(-88.273 -77.146)\"><\/path><\/g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEntreprises de construction\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98feb14 elementor-widget elementor-widget-text-editor\" data-id=\"98feb14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eurohinca travaille en tant que sous-traitant pour des entreprises de construction renomm\u00e9es lorsque le tunnel fait partie d'un projet plus vaste.<\/p><p>Nous conseillons l'entreprise de construction dans le processus de planification et proposons son ex\u00e9cution.<\/p><p>Comme nous avons la classification la plus \u00e9lev\u00e9e pour ses activit\u00e9s, nous sommes ouverts \u00e0 d'autres types de collaboration tels que les UTES (entreprises conjointes temporaires) ou les entreprises conjointes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0518563 e-flex e-con-boxed e-con e-parent\" data-id=\"0518563\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0170cbb e-con-full e-flex e-con e-child\" data-id=\"0170cbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e3d436 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7e3d436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"84\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/icono-inge.svg\" class=\"attachment-full size-full wp-image-1686\" alt=\"ing\u00e9nierie\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Ing\u00e9nierie<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a91c95a elementor-widget elementor-widget-text-editor\" data-id=\"a91c95a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Une partie importante de l'activit\u00e9 d'Eurohinca est consacr\u00e9e \u00e0 la diffusion des diff\u00e9rentes m\u00e9thodes de construction des forages, et \u00e0 la collaboration avec les principales soci\u00e9t\u00e9s d'ing\u00e9nierie dans l'\u00e9laboration de tous les types de projets de tunnels.<\/p><p>Nous pouvons utiliser toute l'exp\u00e9rience que nous avons accumul\u00e9e pour structurer un projet de mise en \u0153uvre r\u00e9alisable avec la proc\u00e9dure la plus appropri\u00e9e et la plus efficace sur le plan \u00e9conomique.<\/p><p>De nombreux facteurs doivent \u00eatre pris en compte dans l'\u00e9laboration d'un projet de tunnel :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93bbc33 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"93bbc33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> G\u00e9ologie : caract\u00e9ristiques g\u00e9otechniques de la roche, du sol, du sable, de la nappe phr\u00e9atique, etc.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rev\u00eatement \u00e0 utiliser : segments, poutrelles, fon\u00e7age de tuyaux.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Disposition : avec des courbes verticales ou horizontales.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Machines de forage : tunnelier \u00e0 bouclier ferm\u00e9 (Hydroshield ou EPB TBM) ou tunnelier \u00e0 bouclier ouvert.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Empresa Nuestra Empresa Investigaci\u00f3n + Desarrollo + Innovaci\u00f3n Desde hace ya varios a\u00f1os Eurohinca participa en programas de I + D + i. Colaborando con universidades y centros tecnol\u00f3gicos con el fin de mejorar la producci\u00f3n y eficacia de todas las actividades de la empresa. A\u00f1os de Experiencia 20 Obras + 240 Kil\u00f3metros + 110 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-60","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eurohinca | Empresa de obra subterr\u00e1nea<\/title>\n<meta name=\"description\" content=\"Conoce Eurohinca, empresa especializada en t\u00faneles y microt\u00faneles sin zanja desde 1996, con proyectos en Espa\u00f1a y mercados internacionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurohinca.com\/fr\/entreprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurohinca | Empresa de obra subterr\u00e1nea\" \/>\n<meta property=\"og:description\" content=\"Conoce Eurohinca, empresa especializada en t\u00faneles y microt\u00faneles sin zanja desde 1996, con proyectos en Espa\u00f1a y mercados internacionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurohinca.com\/fr\/entreprise\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurohinca\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:18:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/LOGO-eurohinca-group.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/\",\"name\":\"Eurohinca | Empresa de obra subterr\u00e1nea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/LOGO-eurohinca-group.png\",\"datePublished\":\"2024-01-26T12:41:08+00:00\",\"dateModified\":\"2026-05-13T10:18:53+00:00\",\"description\":\"Conoce Eurohinca, empresa especializada en t\u00faneles y microt\u00faneles sin zanja desde 1996, con proyectos en Espa\u00f1a y mercados internacionales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/LOGO-eurohinca-group.png\",\"contentUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/LOGO-eurohinca-group.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/empresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\",\"name\":\"Eurohinca\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#organization\",\"name\":\"Eurohinca\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-nuevo.png\",\"contentUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-nuevo.png\",\"width\":512,\"height\":131,\"caption\":\"Eurohinca\"},\"image\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entreprise et expertise | Eurohinca","description":"D\u00e9couvrez Eurohinca, entreprise sp\u00e9cialis\u00e9e en tunnels et microtunnels sans tranch\u00e9e depuis 1996, avec des projets internationaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurohinca.com\/fr\/entreprise\/","og_locale":"fr_FR","og_type":"article","og_title":"Eurohinca | Empresa de obra subterr\u00e1nea","og_description":"Conoce Eurohinca, empresa especializada en t\u00faneles y microt\u00faneles sin zanja desde 1996, con proyectos en Espa\u00f1a y mercados internacionales.","og_url":"https:\/\/eurohinca.com\/fr\/entreprise\/","og_site_name":"Eurohinca","article_modified_time":"2026-05-13T10:18:53+00:00","og_image":[{"url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/LOGO-eurohinca-group.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eurohinca.com\/empresa\/","url":"https:\/\/eurohinca.com\/empresa\/","name":"Entreprise et expertise | Eurohinca","isPartOf":{"@id":"https:\/\/eurohinca.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurohinca.com\/empresa\/#primaryimage"},"image":{"@id":"https:\/\/eurohinca.com\/empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/LOGO-eurohinca-group.png","datePublished":"2024-01-26T12:41:08+00:00","dateModified":"2026-05-13T10:18:53+00:00","description":"D\u00e9couvrez Eurohinca, entreprise sp\u00e9cialis\u00e9e en tunnels et microtunnels sans tranch\u00e9e depuis 1996, avec des projets internationaux.","breadcrumb":{"@id":"https:\/\/eurohinca.com\/empresa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurohinca.com\/empresa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eurohinca.com\/empresa\/#primaryimage","url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/LOGO-eurohinca-group.png","contentUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/LOGO-eurohinca-group.png"},{"@type":"BreadcrumbList","@id":"https:\/\/eurohinca.com\/empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eurohinca.com\/es\/"},{"@type":"ListItem","position":2,"name":"Empresa"}]},{"@type":"WebSite","@id":"https:\/\/eurohinca.com\/es\/#website","url":"https:\/\/eurohinca.com\/es\/","name":"Eurohinca","description":"","publisher":{"@id":"https:\/\/eurohinca.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurohinca.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eurohinca.com\/es\/#organization","name":"Eurohinca","url":"https:\/\/eurohinca.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eurohinca.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/01\/Logo-nuevo.png","contentUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/01\/Logo-nuevo.png","width":512,"height":131,"caption":"Eurohinca"},"image":{"@id":"https:\/\/eurohinca.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":18,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages\/60\/revisions"}],"predecessor-version":[{"id":5553,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages\/60\/revisions\/5553"}],"wp:attachment":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/media?parent=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}