{"id":3555,"date":"2025-02-13T11:14:41","date_gmt":"2025-02-13T11:14:41","guid":{"rendered":"https:\/\/eurohinca.com\/?page_id=3555"},"modified":"2025-02-13T11:17:12","modified_gmt":"2025-02-13T11:17:12","slug":"la-granja-collector","status":"publish","type":"page","link":"https:\/\/eurohinca.com\/fr\/obras\/colector-la-granja\/","title":{"rendered":"Collecteur La Granja"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3555\" class=\"elementor elementor-3555\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aac9b50 e-flex e-con-boxed e-con e-parent\" data-id=\"aac9b50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47e5ff2 elementor-widget elementor-widget-heading\" data-id=\"47e5ff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Collecteur La Grana<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-91786ed e-flex e-con-boxed e-con e-parent\" data-id=\"91786ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8d95e6e e-con-full e-flex e-con e-child\" data-id=\"8d95e6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6cdb7a elementor-widget elementor-widget-text-editor\" data-id=\"c6cdb7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-pm-slice=\"1 1 []\">R\u00e9cup\u00e9ration du domaine public hydraulique dans le ruisseau Arroyo de las Flores.<\/h2><p data-pm-slice=\"1 1 []\">Le projet de la <strong>Collecteur d'eaux us\u00e9es \u00e0 La Granja de San Ildefonso (Segovia)<\/strong> a consist\u00e9 en la construction d'une infrastructure souterraine destin\u00e9e \u00e0 am\u00e9liorer le drainage et la canalisation de l'eau dans la r\u00e9gion d'Arroyo de las Flores. Les travaux ont \u00e9t\u00e9 r\u00e9alis\u00e9s \u00e0 l'aide d'un syst\u00e8me de drainage souterrain. <strong>Bouclier Hidroshield DN2500<\/strong>con\u00e7u pour traverser des terrains granitiques abrasifs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc4ac98 e-con-full e-flex e-con e-child\" data-id=\"dc4ac98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b76b702 elementor-widget elementor-widget-image\" data-id=\"b76b702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"518\" height=\"305\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Imagen-25.png\" class=\"attachment-large size-large wp-image-1765\" alt=\"Collecteur La Granja\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ead41f8 e-flex e-con-boxed e-con e-parent\" data-id=\"ead41f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8519fca e-con-full e-flex e-con e-child\" data-id=\"8519fca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e849785 elementor-widget elementor-widget-text-editor\" data-id=\"e849785\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>D\u00e9tails g\u00e9n\u00e9raux du projet<\/strong><\/h2><ul data-spread=\"false\" data-pm-slice=\"3 5 []\"><li><p><strong>Localisation<\/strong>Date de naissance : La Granja de San Ildefonso, Segovia, Espagne<\/p><\/li><li><p><strong>Objectif principal<\/strong>R\u00e9cup\u00e9ration du domaine public hydrique par la canalisation de l'Arroyo de las Flores.<\/p><\/li><li><p><strong>Conditions g\u00e9ologiques<\/strong>Granit abrasif.<\/p><\/li><li><p><strong>Technologie utilis\u00e9e<\/strong>Bouclier Hydroshield DN2500.<\/p><\/li><li><p><strong>Longueur totale du tunnel<\/strong>Le nombre d'heures de travail est de : 170 m\u00e8tres.<\/p><\/li><li><p><strong>Sections de forage<\/strong>:<\/p><ul data-spread=\"false\"><li><p>100 m\u00e8tres sur le rocher.<\/p><\/li><li><p>70 m\u00e8tres sur le rocher.<\/p><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5bd38e6 e-con-full e-flex e-con e-child\" data-id=\"5bd38e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b178e4 elementor-widget elementor-widget-text-editor\" data-id=\"8b178e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Sp\u00e9cifications techniques<\/strong><\/h2><ul data-spread=\"false\" data-pm-slice=\"3 3 []\"><li><p><strong>Diam\u00e8tre nominal<\/strong>: 2 500 mm.<\/p><\/li><li><p><strong>M\u00e9thode utilis\u00e9e<\/strong>Excavation avec bouclier Hydroshield : Excavation avec bouclier Hydroshield.<\/p><\/li><li><p><strong>Contr\u00f4le de la pression du front de taille<\/strong> pour assurer la stabilit\u00e9 sur les terrains tr\u00e8s accident\u00e9s.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0893f16 e-flex e-con-boxed e-con e-parent\" data-id=\"0893f16\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a031117 e-con-full e-flex e-con e-child\" data-id=\"a031117\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ea5936 elementor-widget elementor-widget-text-editor\" data-id=\"1ea5936\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>D\u00e9fis logistiques et techniques<\/strong><\/h2><p data-pm-slice=\"1 3 []\">Ce projet pr\u00e9sentait des d\u00e9fis en raison du terrain difficile, qui n\u00e9cessitait l'utilisation d'une technologie de pointe et une surveillance constante pendant l'excavation.<\/p><h3>Points forts du projet<\/h3><ul data-spread=\"false\"><li><p><strong>Excavation dans un sol granitique abrasif<\/strong>avec des outils sp\u00e9cialis\u00e9s pour garantir l'efficacit\u00e9 du processus.<\/p><\/li><li><p><strong>Optimisation du syst\u00e8me de drainage<\/strong>l'am\u00e9lioration de la canalisation de l'Arroyo de las Flores.<\/p><\/li><li><p><strong>Utilisation de la technologie Hidroshield<\/strong> pour contr\u00f4ler l'excavation dans les sols \u00e0 haute r\u00e9sistance.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5eb845c e-con-full e-flex e-con e-child\" data-id=\"5eb845c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28146cd elementor-widget elementor-widget-text-editor\" data-id=\"28146cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Impact environnemental et social<\/strong><\/h2><p data-pm-slice=\"1 3 []\">Le collecteur d'\u00e9gouts de La Granja de San Ildefonso am\u00e9liore la capacit\u00e9 de gestion de l'eau dans la r\u00e9gion, garantissant une infrastructure efficace et durable.<\/p><ul data-spread=\"false\"><li><p><strong>R\u00e9duire l'impact sur l'environnement<\/strong>gr\u00e2ce \u00e0 une excavation contr\u00f4l\u00e9e et \u00e0 une canalisation efficace de l'eau.<\/p><\/li><li><p><strong>Une infrastructure moderne et durable<\/strong>con\u00e7u pour optimiser l'\u00e9coulement de l'eau et pr\u00e9venir l'\u00e9rosion.<\/p><\/li><li><p><strong>Am\u00e9lioration du r\u00e9seau de drainage<\/strong>Le projet a \u00e9t\u00e9 con\u00e7u pour assurer l'approvisionnement en eau de la communaut\u00e9 locale et r\u00e9duire le risque d'inondation.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5eb64fd e-flex e-con-boxed e-con e-parent\" data-id=\"5eb64fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d8b340 elementor-widget elementor-widget-heading\" data-id=\"6d8b340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9f\u00e9rences des travaux ex\u00e9cut\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-429748e elementor-widget elementor-widget-text-editor\" data-id=\"429748e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Eurohinca, nous sommes sp\u00e9cialis\u00e9s dans l'ex\u00e9cution de tunnels pour pipelines \u00e0 l'aide de tunneliers. Depuis sa cr\u00e9ation en 1996, Eurohinca a ex\u00e9cut\u00e9 diff\u00e9rents types de travaux :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc4cec3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc4cec3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbd41da\" data-id=\"cbd41da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2575e22 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2575e22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Exp\u00e9rience internationale<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88e0d4c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"88e0d4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Projets dans le monde<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7002eb elementor-widget elementor-widget-image\" data-id=\"f7002eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/EUROHINCA-INTERNATIONAL-EXPERIENCE.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"EUROHINCA-INTERNATIONAL-EXPERIENCE\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQ5MSwidXJsIjoiaHR0cHM6XC9cL2V1cm9oaW5jYS5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAyXC9FVVJPSElOQ0EtSU5URVJOQVRJT05BTC1FWFBFUklFTkNFLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2000\" height=\"989\" src=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/EUROHINCA-INTERNATIONAL-EXPERIENCE.jpg\" class=\"attachment-full size-full wp-image-1491\" alt=\"carte eurohinca\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-249de6f e-flex e-con-boxed e-con e-parent\" data-id=\"249de6f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-718b4ca elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"718b4ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Demande d'information<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1469468 elementor-widget elementor-widget-text-editor\" data-id=\"1469468\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"color: #00a3de;\"><strong>Merci de consid\u00e9rer notre entreprise pour vos propositions commerciales!<\/strong><\/span><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Colector la Grana Recuperaci\u00f3n del dominio p\u00fablico hidr\u00e1ulico en el Arroyo de las Flores El proyecto del colector de saneamiento en La Granja de San Ildefonso (Segovia) consisti\u00f3 en la construcci\u00f3n de una infraestructura subterr\u00e1nea para mejorar el drenaje y la canalizaci\u00f3n de aguas en la zona del Arroyo de las Flores. La obra se [&hellip;]<\/p>\n","protected":false},"author":80,"featured_media":1765,"parent":62,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3555","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colector la Granja - Eurohinca<\/title>\n<meta name=\"description\" content=\"Construcci\u00f3n de conexi\u00f3n entre colectores en la EDAR Lagares con escudo Hidroshield DN2500, optimizando el sistema de saneamiento en terrenos variables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurohinca.com\/fr\/travaux\/la-granja-collector\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colector la Granja - Eurohinca\" \/>\n<meta property=\"og:description\" content=\"Construcci\u00f3n de conexi\u00f3n entre colectores en la EDAR Lagares con escudo Hidroshield DN2500, optimizando el sistema de saneamiento en terrenos variables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurohinca.com\/fr\/travaux\/la-granja-collector\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurohinca\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T11:17:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Imagen-25.png\" \/>\n\t<meta property=\"og:image:width\" content=\"518\" \/>\n\t<meta property=\"og:image:height\" content=\"305\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/\",\"name\":\"Colector la Granja - Eurohinca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Imagen-25.png\",\"datePublished\":\"2025-02-13T11:14:41+00:00\",\"dateModified\":\"2025-02-13T11:17:12+00:00\",\"description\":\"Construcci\u00f3n de conexi\u00f3n entre colectores en la EDAR Lagares con escudo Hidroshield DN2500, optimizando el sistema de saneamiento en terrenos variables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Imagen-25.png\",\"contentUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Imagen-25.png\",\"width\":518,\"height\":305,\"caption\":\"Colector la Granja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/obras\\\/colector-la-granja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obras\",\"item\":\"https:\\\/\\\/eurohinca.com\\\/obras\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Colector la Granja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\",\"name\":\"Eurohinca\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#organization\",\"name\":\"Eurohinca\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-nuevo.png\",\"contentUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-nuevo.png\",\"width\":512,\"height\":131,\"caption\":\"Eurohinca\"},\"image\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collecteur La Granja - Eurohinca","description":"Connexion des collecteurs de la STEP de Lagares avec Hydroshield DN2500 : assainissement optimis\u00e9, s\u00e9curit\u00e9 et contr\u00f4le en terrain variable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurohinca.com\/fr\/travaux\/la-granja-collector\/","og_locale":"fr_FR","og_type":"article","og_title":"Colector la Granja - Eurohinca","og_description":"Construcci\u00f3n de conexi\u00f3n entre colectores en la EDAR Lagares con escudo Hidroshield DN2500, optimizando el sistema de saneamiento en terrenos variables.","og_url":"https:\/\/eurohinca.com\/fr\/travaux\/la-granja-collector\/","og_site_name":"Eurohinca","article_modified_time":"2025-02-13T11:17:12+00:00","og_image":[{"width":518,"height":305,"url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Imagen-25.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/","url":"https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/","name":"Collecteur La Granja - Eurohinca","isPartOf":{"@id":"https:\/\/eurohinca.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/#primaryimage"},"image":{"@id":"https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/#primaryimage"},"thumbnailUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Imagen-25.png","datePublished":"2025-02-13T11:14:41+00:00","dateModified":"2025-02-13T11:17:12+00:00","description":"Connexion des collecteurs de la STEP de Lagares avec Hydroshield DN2500 : assainissement optimis\u00e9, s\u00e9curit\u00e9 et contr\u00f4le en terrain variable.","breadcrumb":{"@id":"https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/#primaryimage","url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Imagen-25.png","contentUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/02\/Imagen-25.png","width":518,"height":305,"caption":"Colector la Granja"},{"@type":"BreadcrumbList","@id":"https:\/\/eurohinca.com\/es\/obras\/colector-la-granja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eurohinca.com\/es\/"},{"@type":"ListItem","position":2,"name":"Obras","item":"https:\/\/eurohinca.com\/obras\/"},{"@type":"ListItem","position":3,"name":"Colector la Granja"}]},{"@type":"WebSite","@id":"https:\/\/eurohinca.com\/es\/#website","url":"https:\/\/eurohinca.com\/es\/","name":"Eurohinca","description":"","publisher":{"@id":"https:\/\/eurohinca.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurohinca.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eurohinca.com\/es\/#organization","name":"Eurohinca","url":"https:\/\/eurohinca.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eurohinca.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/01\/Logo-nuevo.png","contentUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/01\/Logo-nuevo.png","width":512,"height":131,"caption":"Eurohinca"},"image":{"@id":"https:\/\/eurohinca.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages\/3555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/comments?post=3555"}],"version-history":[{"count":4,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages\/3555\/revisions"}],"predecessor-version":[{"id":3559,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages\/3555\/revisions\/3559"}],"up":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/pages\/62"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/media\/1765"}],"wp:attachment":[{"href":"https:\/\/eurohinca.com\/fr\/wp-json\/wp\/v2\/media?parent=3555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}