{"id":373,"date":"2018-06-12T06:24:00","date_gmt":"2018-06-12T06:24:00","guid":{"rendered":"https:\/\/eurohinca.es\/?p=373"},"modified":"2024-02-05T07:45:18","modified_gmt":"2024-02-05T07:45:18","slug":"sur-de-texas-tuxpan-altamira-landfall","status":"publish","type":"post","link":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/","title":{"rendered":"SUR DE TEXAS &#8211; TUXPAN, ALTAMIRA LANDFALL"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"373\" class=\"elementor elementor-373\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52a1fa6 e-flex e-con-boxed e-con e-parent\" data-id=\"52a1fa6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-492aaa6 elementor-widget elementor-widget-text-editor\" data-id=\"492aaa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En el marco del proyecto\u00a0<i>Gasoducto Sur de Texas &#8211; Tuxpan\u00a0<\/i>, Terratest Tunnelling ha desarrollado el dise\u00f1o y construcci\u00f3n del ramal de Altamira: record mundial de 2246 m excavados con tuneladora hidroescudo con hinca de tuber\u00eda de hormig\u00f3n armado y rescate submarino de la tuneladora.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7782a1 elementor-widget elementor-widget-button\" data-id=\"b7782a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/trenchlesstechnology.com\/building-big-with-microtunneling-terratest-mexico\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00e1s informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En el marco del proyecto\u00a0Gasoducto Sur de Texas &#8211; Tuxpan\u00a0, Terratest Tunnelling ha desarrollado el dise\u00f1o y construcci\u00f3n del ramal de Altamira: record mundial de 2246 m excavados con tuneladora hidroescudo con hinca de tuber\u00eda de hormig\u00f3n armado y rescate submarino de la tuneladora. M\u00e1s informaci\u00f3n<\/p>\n","protected":false},"author":2,"featured_media":381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SUR DE TEXAS - TUXPAN, ALTAMIRA LANDFALL - Eurohinca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SUR DE TEXAS - TUXPAN, ALTAMIRA LANDFALL - Eurohinca\" \/>\n<meta property=\"og:description\" content=\"En el marco del proyecto\u00a0Gasoducto Sur de Texas &#8211; Tuxpan\u00a0, Terratest Tunnelling ha desarrollado el dise\u00f1o y construcci\u00f3n del ramal de Altamira: record mundial de 2246 m excavados con tuneladora hidroescudo con hinca de tuber\u00eda de hormig\u00f3n armado y rescate submarino de la tuneladora. M\u00e1s informaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurohinca\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-12T06:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T07:45:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurohinca.com\/wp-content\/uploads\/2018\/06\/record.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ashuser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ashuser\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/\"},\"author\":{\"name\":\"ashuser\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/person\\\/43a5ae944550b6a72fa179dfd8034439\"},\"headline\":\"SUR DE TEXAS &#8211; TUXPAN, ALTAMIRA LANDFALL\",\"datePublished\":\"2018-06-12T06:24:00+00:00\",\"dateModified\":\"2024-02-05T07:45:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/\"},\"wordCount\":59,\"publisher\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/record.jpg\",\"articleSection\":[\"2018\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/\",\"name\":\"SUR DE TEXAS - TUXPAN, ALTAMIRA LANDFALL - Eurohinca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/record.jpg\",\"datePublished\":\"2018-06-12T06:24:00+00:00\",\"dateModified\":\"2024-02-05T07:45:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/record.jpg\",\"contentUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/record.jpg\",\"width\":1280,\"height\":720,\"caption\":\"record the longest sea outfall\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/sur-de-texas-tuxpan-altamira-landfall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eurohinca.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SUR DE TEXAS &#8211; TUXPAN, ALTAMIRA LANDFALL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\",\"name\":\"Eurohinca\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#organization\",\"name\":\"Eurohinca\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-nuevo.png\",\"contentUrl\":\"https:\\\/\\\/eurohinca.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo-nuevo.png\",\"width\":512,\"height\":131,\"caption\":\"Eurohinca\"},\"image\":{\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eurohinca.com\\\/es\\\/#\\\/schema\\\/person\\\/43a5ae944550b6a72fa179dfd8034439\",\"name\":\"ashuser\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SUR DE TEXAS - TUXPAN, ALTAMIRA LANDFALL - Eurohinca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/","og_locale":"es_ES","og_type":"article","og_title":"SUR DE TEXAS - TUXPAN, ALTAMIRA LANDFALL - Eurohinca","og_description":"En el marco del proyecto\u00a0Gasoducto Sur de Texas &#8211; Tuxpan\u00a0, Terratest Tunnelling ha desarrollado el dise\u00f1o y construcci\u00f3n del ramal de Altamira: record mundial de 2246 m excavados con tuneladora hidroescudo con hinca de tuber\u00eda de hormig\u00f3n armado y rescate submarino de la tuneladora. M\u00e1s informaci\u00f3n","og_url":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/","og_site_name":"Eurohinca","article_published_time":"2018-06-12T06:24:00+00:00","article_modified_time":"2024-02-05T07:45:18+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2018\/06\/record.jpg","type":"image\/jpeg"}],"author":"ashuser","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ashuser","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/#article","isPartOf":{"@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/"},"author":{"name":"ashuser","@id":"https:\/\/eurohinca.com\/es\/#\/schema\/person\/43a5ae944550b6a72fa179dfd8034439"},"headline":"SUR DE TEXAS &#8211; TUXPAN, ALTAMIRA LANDFALL","datePublished":"2018-06-12T06:24:00+00:00","dateModified":"2024-02-05T07:45:18+00:00","mainEntityOfPage":{"@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/"},"wordCount":59,"publisher":{"@id":"https:\/\/eurohinca.com\/es\/#organization"},"image":{"@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/#primaryimage"},"thumbnailUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2018\/06\/record.jpg","articleSection":["2018"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/","url":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/","name":"SUR DE TEXAS - TUXPAN, ALTAMIRA LANDFALL - Eurohinca","isPartOf":{"@id":"https:\/\/eurohinca.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/#primaryimage"},"image":{"@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/#primaryimage"},"thumbnailUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2018\/06\/record.jpg","datePublished":"2018-06-12T06:24:00+00:00","dateModified":"2024-02-05T07:45:18+00:00","breadcrumb":{"@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/#primaryimage","url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2018\/06\/record.jpg","contentUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2018\/06\/record.jpg","width":1280,"height":720,"caption":"record the longest sea outfall"},{"@type":"BreadcrumbList","@id":"https:\/\/eurohinca.com\/es\/sur-de-texas-tuxpan-altamira-landfall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eurohinca.com\/"},{"@type":"ListItem","position":2,"name":"SUR DE TEXAS &#8211; TUXPAN, ALTAMIRA LANDFALL"}]},{"@type":"WebSite","@id":"https:\/\/eurohinca.com\/es\/#website","url":"https:\/\/eurohinca.com\/es\/","name":"Eurohinca","description":"","publisher":{"@id":"https:\/\/eurohinca.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurohinca.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eurohinca.com\/es\/#organization","name":"Eurohinca","url":"https:\/\/eurohinca.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurohinca.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/01\/Logo-nuevo.png","contentUrl":"https:\/\/eurohinca.com\/wp-content\/uploads\/2024\/01\/Logo-nuevo.png","width":512,"height":131,"caption":"Eurohinca"},"image":{"@id":"https:\/\/eurohinca.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eurohinca.com\/es\/#\/schema\/person\/43a5ae944550b6a72fa179dfd8034439","name":"ashuser"}]}},"_links":{"self":[{"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/posts\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":0,"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/posts\/373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/media\/381"}],"wp:attachment":[{"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/media?parent=373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/categories?post=373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurohinca.com\/es\/wp-json\/wp\/v2\/tags?post=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}